{"id":263,"date":"2020-01-14T14:14:39","date_gmt":"2020-01-14T13:14:39","guid":{"rendered":"http:\/\/maywaldconsulting.com\/website\/?page_id=263"},"modified":"2021-02-24T15:30:57","modified_gmt":"2021-02-24T14:30:57","slug":"chi-siamo","status":"publish","type":"page","link":"https:\/\/maywaldconsulting.com\/website\/chi-siamo\/","title":{"rendered":"Chi siamo"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"263\" class=\"elementor elementor-263\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8470c73 elementor-section-stretched elementor-section-full_width elementor-section-height-min-height elementor-section-content-middle elementor-section-height-default elementor-section-items-middle\" data-id=\"8470c73\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-79f54da\" data-id=\"79f54da\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1520e7d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1520e7d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4f4bbd3\" data-id=\"4f4bbd3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58f9dda animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"58f9dda\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;,&quot;_animation_delay&quot;:500}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2020\/01\/Icon-Maywald-Consulting-Color-Outline-Mediumn-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-57\" alt=\"Icona Logo Maywald Consulting Outline\" srcset=\"https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2020\/01\/Icon-Maywald-Consulting-Color-Outline-Mediumn-150x150.png 150w, https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2020\/01\/Icon-Maywald-Consulting-Color-Outline-Mediumn-300x300.png 300w, https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2020\/01\/Icon-Maywald-Consulting-Color-Outline-Mediumn.png 500w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f689621 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"f689621\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:1000}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">FUNDRAISING AND MORE<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ac7f44f elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"ac7f44f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7524e9d\" data-id=\"7524e9d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6a8c09e elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6a8c09e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-898aea0\" data-id=\"898aea0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6dc3ad5 elementor-widget elementor-widget-heading\" data-id=\"6dc3ad5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Maywald Consulting \u00e8 una agenzia di consulenza che fornisce servizi, soluzioni e affiancamento per ottenere risultati di alto livello nella raccolta di fondi.<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dad39cf elementor-widget elementor-widget-text-editor\" data-id=\"dad39cf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Collaboriamo con le organizzazioni non profit per individuare le strategie di raccolta fondi pi\u00f9 efficaci nel &nbsp;raggiungere i propri obiettivi.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1179f2d elementor-widget elementor-widget-text-editor\" data-id=\"1179f2d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Forniamo ai nostri clienti strumenti e soluzioni per uno <strong>sviluppo sostenibile<\/strong> e per operare in un mercato sempre pi\u00f9 complesso e affollato.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41a06db elementor-widget elementor-widget-text-editor\" data-id=\"41a06db\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Sosteniamo le organizzazioni non profit nella realizzazione di progetti di raccolta fondi sia nella fase di start up che nello sviluppo di specifici programmi o progetti.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23c02e7 elementor-widget elementor-widget-text-editor\" data-id=\"23c02e7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Uniamo la nostra attivit\u00e0 di consulenza con una profonda conoscenza del mercato italiano, dei processi e delle tecniche.<span class=\"Apple-converted-space\">\u00a0<\/span>Il nostro approccio \u00e8 orientato all&#8217;efficienza e puntiamo a risultati misurabili.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2a372b elementor-widget elementor-widget-text-editor\" data-id=\"f2a372b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Il team <strong>Maywald Consulting<\/strong> si compone di professionisti con una consolidata e diversificata esperienza nelle varie tecniche di raccolta fondi, maturata all&#8217;interno di organizzazioni non profit di livello nazionale ed internazionale.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-424b5f6 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"424b5f6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fa8f118\" data-id=\"fa8f118\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70f58bc elementor-widget elementor-widget-heading\" data-id=\"70f58bc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">OUR MISSION<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc7583d elementor-widget elementor-widget-text-editor\" data-id=\"cc7583d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Maywald Consulting aiuta a sviluppare le competenze dei Fundraisers e dei professionisti del non profit affinch\u00e8 aumentino in modo significativo la loro capacit\u00e0 di raccolta fondi e relativo impatto sui loro beneficiari, sulle loro comunit\u00e0 e la societ\u00e0 civile.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-abef0a7\" data-id=\"abef0a7\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7596309 elementor-widget elementor-widget-heading\" data-id=\"7596309\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">OUR VISION<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f7ba33 elementor-widget elementor-widget-text-editor\" data-id=\"6f7ba33\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Crediamo con fermezza che il ruolo del <strong>Fundraiser<\/strong> sia determinante per la crescita del Welfare nel nostro Paese e che esistano concrete opportunit\u00e0 di migliorare l\u2019impatto della raccolta fondi attraverso lo scambio delle buone prassi e lo sviluppo continuo delle competenze.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-660f3b5 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"660f3b5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0bea55f\" data-id=\"0bea55f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-87ae17d elementor-widget elementor-widget-heading\" data-id=\"87ae17d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Scopri le due anime della nostra sola passione!<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-53fdb504 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"53fdb504\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-30173967\" data-id=\"30173967\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f68e069 elementor-widget elementor-widget-heading\" data-id=\"6f68e069\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">CONSULENZA<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-198d9c7e elementor-widget elementor-widget-text-editor\" data-id=\"198d9c7e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Consulenza strategica e operativa nell&#8217;ambito del fundraising<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75af02ae elementor-align-center elementor-widget elementor-widget-button\" data-id=\"75af02ae\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"https:\/\/maywaldconsulting.com\/website\/consulenza\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">LEGGI TUTTO<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-11c8c88f\" data-id=\"11c8c88f\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d67307 elementor-widget elementor-widget-heading\" data-id=\"7d67307\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">FORMAZIONE<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f702dc2 elementor-widget elementor-widget-text-editor\" data-id=\"3f702dc2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Percorsi formativi professionali per tutti i livelli di specializzazione<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-548b49e5 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"548b49e5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"https:\/\/maywaldconsulting.com\/website\/formazione\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">LEGGI TUTTO<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3fa4bf35 elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3fa4bf35\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-734c4ea2\" data-id=\"734c4ea2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31906811 elementor-widget elementor-widget-heading\" data-id=\"31906811\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Cosa dicono di noi?<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4720d2a3 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4720d2a3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-33915ca3\" data-id=\"33915ca3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d6e0321 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"1d6e0321\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon elementor-animation-grow\">\n\t\t\t\t\t\t\t<i class=\"fa fa-quote-left\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73be8dc4 elementor-widget elementor-widget-testimonial\" data-id=\"73be8dc4\" data-element_type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\"><i>\u201cHo avuto il piacere di lavorare con Laura per tutta la durata della sua consulenza per Fondazione Umberto Veronesi. Il suo supporto \u00e8 stato fondamentale per la campagna di raccolta fondi dedicata ai lasciti testamentari e per la pianificazione e sviluppo strategico sul target Major Donor. La competenza di Laura in ambito di raccolta fondi e la sua profonda conoscenza delle organizzazioni del terzo settore hanno portato ulteriore valore al lavoro svolto e allo staff interno che ha collaborato con lei\u201d\n<\/i><\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-name\">Ferdinando Ricci - Fondazione Umberto Veronesi<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-job\">Responsabile Marketing<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-12c81fc1\" data-id=\"12c81fc1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-597914da elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"597914da\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon elementor-animation-grow\">\n\t\t\t\t\t\t\t<i class=\"fa fa-quote-left\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35e107b9 elementor-widget elementor-widget-testimonial\" data-id=\"35e107b9\" data-element_type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\"><i>La collaborazione si \u00e8 rivelata immediatamente dinamica, fattiva e proficua.\nE\u2019 stata per me un\u2019esperienza indimenticabile. <i>L\u2019alta professionalit\u00e0, l\u2019approccio umano e personalizzato, la coerenza e la motivazione di Laura, unite alla mia determinazione e passione, hanno fatto in modo che Oncologia per l\u2019Africa assumesse, da subito, una veste manageriale e portasse a compimento e con successo gli obiettivi prefissati.<\/i><\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-name\">Titti Andriani - Oncologia per l\u2019Africa Onlus<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-job\">Presidente<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-37a65459 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"37a65459\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7d62a7ae\" data-id=\"7d62a7ae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dcecdc1 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"dcecdc1\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon elementor-animation-grow\">\n\t\t\t\t\t\t\t<i class=\"fa fa-quote-left\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-394547cc elementor-widget elementor-widget-testimonial\" data-id=\"394547cc\" data-element_type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\"><i>\"Laura \u00e8 tra i 10 migliori esperti di fundraising in Italia. La sua professionalit\u00e0 mista alla sua passione ed energia mettono le organizzazioni nelle condizioni di trovare le soluzioni pratiche di cui hanno bisogno. Con la sua esperienza Laura \u00e8 in grado di sviluppare soluzioni flessibili adattabili a differenti contesti e a beneficio dell'organizzazione\"\n<\/i><\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-name\">Donatella Massai - World Health Organization<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-job\">Senior Consultant<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2ac489e\" data-id=\"2ac489e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20748173 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"20748173\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon elementor-animation-grow\">\n\t\t\t\t\t\t\t<i class=\"fa fa-quote-left\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c7d5b7d elementor-widget elementor-widget-testimonial\" data-id=\"7c7d5b7d\" data-element_type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\"><i>\"Ho lavorato con Laura quattro anni in Amnesty International - Sezione Italiana, Dipartimento Marketing. E' una fundraiser brillante, con una grande capacit\u00e0 di leggere \u00a0i contesti ed eleaborare strategie. La sua consolidata esperienza nella raccolta fondi e nel marketing si fonde con una mentalit\u00e0 aperta che le consente di cogliere le opportunit\u00e0 e le sfide delle nuove tecnologie\"\n<\/i><\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-name\">Annalaura Anselmi - Medici Senza Frontiere Italia<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-job\">Direttrice raccolta fondi<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-771dca62 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"771dca62\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-23669a7c\" data-id=\"23669a7c\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50fe0845 elementor-widget elementor-widget-image\" data-id=\"50fe0845\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2020\/01\/Laura-Maywald-Round-2.png\" class=\"elementor-animation-grow attachment-large size-large wp-image-1074\" alt=\"Laura Maywald\" srcset=\"https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2020\/01\/Laura-Maywald-Round-2.png 1000w, https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2020\/01\/Laura-Maywald-Round-2-300x300.png 300w, https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2020\/01\/Laura-Maywald-Round-2-150x150.png 150w, https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2020\/01\/Laura-Maywald-Round-2-768x768.png 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41be5857 elementor-widget elementor-widget-heading\" data-id=\"41be5857\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">LAURA MAYWALD<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12dfdc53 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"12dfdc53\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40a1be59 elementor-widget elementor-widget-heading\" data-id=\"40a1be59\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Maywald Consulting founder<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-42a75b97\" data-id=\"42a75b97\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2930801e elementor-widget elementor-widget-text-editor\" data-id=\"2930801e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Laura Maywald, consulente senior e managing director di Maywald Consulting.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74c2f307 elementor-widget elementor-widget-text-editor\" data-id=\"74c2f307\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Laura ha collaborato per 18 anni con organizzazioni nazionali e internazionali quali Greenpeace e Amnesty International ricoprendo il ruolo di direttrice della raccolta fondi.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a2bf842 elementor-widget elementor-widget-text-editor\" data-id=\"5a2bf842\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Nel 2010 fonda la Maywald Consulting, agenzia che offre\u00a0consulenza strategica e operativa\u00a0nell\u2019ambito del\u00a0fundraising\u00a0per piccole, medie e grandi organizzazioni nazionali\u00a0e\u00a0internazionali <br \/>mettendo al servizio delle organizzazioni una consolidata esperienza nelle aree legate alle\u00a0tecniche di raccolta fondi, nonch\u00e9 nella\u00a0predisposizione e sviluppo di specifici progetti.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0d70e2 elementor-widget elementor-widget-text-editor\" data-id=\"d0d70e2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Laura \u00e8 Vice Presidente di Greenpeace Italia, membro del Consiglio direttivo di Sightsavers Italy, e membro dell\u2019Advisory Board di Intersos.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-623e400a elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"623e400a\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-50c64b0c\" data-id=\"50c64b0c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12c70999 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"12c70999\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;9&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;pause_on_hover&quot;:&quot;no&quot;,&quot;autoplay_speed&quot;:2000,&quot;speed&quot;:1000,&quot;slides_to_show_tablet&quot;:&quot;5&quot;,&quot;slides_to_show_mobile&quot;:&quot;3&quot;,&quot;slides_to_scroll_tablet&quot;:&quot;1&quot;,&quot;slides_to_scroll_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"rtl\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 23\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2020\/01\/MC_loghi-14-150x150-1-1-150x150.jpg\" alt=\"afron\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 23\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2020\/01\/MC_loghi-13-150x150-1-1-150x150.jpg\" alt=\"amka\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 23\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2020\/01\/MC_loghi-12-150x150-1-1-150x150.jpg\" alt=\"marevivo\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 di 23\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2020\/01\/MC_loghi-11-150x150-1-1-150x150.jpg\" alt=\"agire\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 di 23\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2020\/01\/MC_loghi-09-150x150-1-1-150x150.jpg\" alt=\"save the children\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 di 23\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2020\/01\/MC_loghi-08-150x150-1-1-150x150.jpg\" alt=\"21 luglio\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 di 23\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2020\/01\/MC_loghi-07-150x150-1-1-150x150.jpg\" alt=\"testamento solidale\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 di 23\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2020\/01\/MC_loghi-06-150x150-1-1-150x150.jpg\" alt=\"fondazione umberto veronesi\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 di 23\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2020\/01\/MC_loghi-05-150x150-1-1-150x150.jpg\" alt=\"amref\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 di 23\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2020\/01\/MC_loghi-04-150x150-1-1-150x150.jpg\" alt=\"intersos\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 di 23\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2020\/01\/ACS-150x150-1-1-150x150.jpg\" alt=\"Aiuto alla chiesa che soffre\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 di 23\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2020\/01\/cappodarco-150x150-1-1-150x150.png\" alt=\"capodarco\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 di 23\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2020\/01\/MC_loghi-02-150x150-1-1-150x150.jpg\" alt=\"lega del filo d&#039;oro\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 di 23\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2020\/01\/MC_loghi-03-150x150-1-1-150x150.jpg\" alt=\"Medici senza frontiere\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 di 23\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2020\/01\/MC_loghi-17-RECON-150x150-1-1-150x150.png\" alt=\"Re:common\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 di 23\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2020\/01\/MC_loghi-18-arkinson-150x150-1-1-150x150.jpg\" alt=\"Parkinson Italia\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"17 di 23\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2020\/10\/Community-Organizing-Cliente-Maywald-Consulting-150x150.jpg\" alt=\"loghi\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"18 di 23\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2020\/10\/Helpcode-Cliente-Maywald-Consulting-150x150.jpg\" alt=\"Helpcode Cliente Maywald Consulting\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"19 di 23\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2021\/02\/AIL-150x150.png\" alt=\"AIL\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"20 di 23\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2021\/02\/Senza-titolo-1-150x150.jpg\" alt=\"Senza-titolo-1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"21 di 23\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2021\/02\/Medecins-du-monde-150x150.jpg\" alt=\"Medecins-du-monde\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"22 di 23\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2021\/02\/AISM-1-150x150.jpg\" alt=\"AISM\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"23 di 23\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/maywaldconsulting.com\/website\/wp-content\/uploads\/2021\/02\/Sport-Senza-Frontiere-1-150x150.jpg\" alt=\"Sport-Senza-Frontiere\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>FUNDRAISING AND MORE Maywald Consulting \u00e8 una agenzia di consulenza che fornisce servizi, soluzioni e affiancamento per ottenere risultati di alto livello nella raccolta di fondi. Collaboriamo con le organizzazioni non profit per individuare le strategie di raccolta fondi pi\u00f9 efficaci nel &nbsp;raggiungere i propri obiettivi. Forniamo ai nostri clienti strumenti e soluzioni per uno [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"rank_math_lock_modified_date":false,"_lmt_disableupdate":"no","_lmt_disable":"yes","footnotes":""},"class_list":["post-263","page","type-page","status-publish","hentry","entry"],"_links":{"self":[{"href":"https:\/\/maywaldconsulting.com\/website\/wp-json\/wp\/v2\/pages\/263"}],"collection":[{"href":"https:\/\/maywaldconsulting.com\/website\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/maywaldconsulting.com\/website\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/maywaldconsulting.com\/website\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/maywaldconsulting.com\/website\/wp-json\/wp\/v2\/comments?post=263"}],"version-history":[{"count":0,"href":"https:\/\/maywaldconsulting.com\/website\/wp-json\/wp\/v2\/pages\/263\/revisions"}],"wp:attachment":[{"href":"https:\/\/maywaldconsulting.com\/website\/wp-json\/wp\/v2\/media?parent=263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}